{"id":7036,"date":"2024-07-15T20:47:51","date_gmt":"2024-07-15T17:47:51","guid":{"rendered":"https:\/\/iicbarcellona.esteri.it\/?page_id=7036"},"modified":"2024-07-15T20:47:51","modified_gmt":"2024-07-15T17:47:51","slug":"archivio-eventi","status":"publish","type":"page","link":"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/archivio-eventi\/","title":{"rendered":"Archivio eventi"},"content":{"rendered":"        <div class=\"row\">\n\t\t\t<!-- Ricerca sedi post -->\n\t\t\t<div class=\"col-12 mt-4\">\n\t\t\t  <div class=\"callout callout-highlight note ricerca-esteri p-4\">\n                    <div class=\"callout-title\">\n                        <svg class=\"icon\">\n                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-search\"><\/use>\n                        <\/svg>Inserisci i parametri di ricerca                    <\/div>\n                    <form id=\"searchFormPost\" name=\"form-search-post\" class=\"form-row align-items-center\" action=\"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036\/\" method=\"GET\"> \n                        <!-- <div class=\"form-group pt-5\"> -->\n                            <!-- <input type=\"hidden\" id=\"lang\" name=\"lang\" value=\"\"> --> <!-- <\/div> -->\n\n                        <div class=\"it-datepicker-wrapper\">\n                            <div class=\"row\">\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-init\">Dal<\/label>\n                                    <input class=\"form-control\" name=\"date-init\" id=\"date-init\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\"lang=\"en-EN\">  \n                                <\/div>\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-end\">Al<\/label>\n                                    <input class=\"form-control\" name=\"date-end\" id=\"date-end\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"form-group col-md-12 mt-3\">\n                            <label for=\"searchText\">Campo ricerca libera<\/label>\n                            <input type=\"text\" name=\"searchText\" class=\"form-control\" id=\"searchText\" value=\"\">\n                        <\/div>\n                        <div class=\"form-group col-md-4 offset-md-8 text-end\">\n                            <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/archivio-eventi\/\" title=\"Form reset\" id=\"resetImput\" class=\"btn btn-outline-primary btn-xs\">Reset<\/a>\n                            <button type=\"submit\" class=\"btn btn-primary btn-xs\">Mostra risultati<\/button>\n                        <\/div>\n                    <\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                    \n            <div class=\"row\">\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/fem-jazz-2026\/\" title=\"Leggi l'articolo: FEM JAZZ 2026\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Copia-FEM-Jazz-2026_Logos-actualizados-240x300.png\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Copia-FEM-Jazz-2026_Logos-actualizados.png 1080w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Copia-FEM-Jazz-2026_Logos-actualizados-240x300.png 240w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Copia-FEM-Jazz-2026_Logos-actualizados-819x1024.png 819w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Copia-FEM-Jazz-2026_Logos-actualizados-768x960.png 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\"  title=\"Copia FEM Jazz 2026_Logos actualizados\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Sab 09 Mag 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/fem-jazz-2026\/\" title=\"FEM JAZZ 2026\">FEM JAZZ 2026<\/a><\/h5>\n                            <p class=\"card-text\">In occasione della Giornata dell\u2019Europa, torna l\u2019appuntamento con il jazz al femminile promosso dal cluster EUNIC Barcelona insieme all\u2019Escola Superior de M\u00fasica de Catalunya, con il sostegno della Commissione Europea a Barcellona, della Diputaci\u00f3 e del Comune: sabato 9 maggio alle ore 19, nella suggestiva Pla\u00e7a del Rei, si esibir\u00e0 un ensemble di eccellenti musiciste [&hellip;]<\/p>\n                                <a title=\"FEM JAZZ 2026\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/fem-jazz-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/intelligenza-artificiale-e-architettura\/\" title=\"Leggi l'articolo: Intelligenza Artificiale e Architettura\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/2-1-212x300.jpg\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/2-1.jpg 1060w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/2-1-212x300.jpg 212w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/2-1-724x1024.jpg 724w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/2-1-768x1087.jpg 768w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\"  title=\"2\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mer 06 Mag 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/intelligenza-artificiale-e-architettura\/\" title=\"Intelligenza Artificiale e Architettura\">Intelligenza Artificiale e Architettura<\/a><\/h5>\n                            <p class=\"card-text\">Il terzo appuntamento degli Aperitivi di Architettura proporr\u00e0 uno spazio di dibattito critico sulla trasformazione digitale del settore dell\u2019architettura, con un incontro su &#8220;Intelligenza Artificiale e Architettura: un confronto tra accademia e professione&#8221;. Con: Manuela Ianni, Estel Ortega, Janina Puig Costa Si esplorer\u00e0 come si stia aggiornando la didattica di fronte all\u2019irruzione delle nuove tecnologie [&hellip;]<\/p>\n                                <a title=\"Intelligenza Artificiale e Architettura\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/intelligenza-artificiale-e-architettura\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/elsa-peretti-days-maria-mauti\/\" title=\"Leggi l'articolo: Elsa Peretti days &#8211; Isabel Coixet\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Isabel-Coixet-EPD-TAK-300x168.jpg\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Isabel-Coixet-EPD-TAK.jpg 560w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/Isabel-Coixet-EPD-TAK-300x168.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\"  title=\"Isabel-Coixet-EPD-TAK\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Ven 01 Mag 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/elsa-peretti-days-maria-mauti\/\" title=\"Elsa Peretti days &#8211; Isabel Coixet\">Elsa Peretti days &#8211; Isabel Coixet<\/a><\/h5>\n                            <p class=\"card-text\">Il Teatre Akad\u00e8mia programma una serie di incontri dedicati alla fondatrice dello spazio culturale, la celebre artista e mecenate Elsa Peretti: un\u2019occasione per approfondire la sua eredit\u00e0 poliedrica e visionaria. 21\/4 &#8211; ore 20: Masterclass della regista Maria Mauti, proiezione di un suo documentario e colloquio con Guido Torlonia 23\/4 &#8211; ore 20: Masterclass della [&hellip;]<\/p>\n                                <a title=\"Elsa Peretti days &#8211; Isabel Coixet\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/elsa-peretti-days-maria-mauti\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/caffe-letterario-alcide-pierantozzi\/\" title=\"Leggi l'articolo: Caff\u00e9 letterario |\u00a0Alcide Pierantozzi\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/03\/Club-di-lettura-240x300.png\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/03\/Club-di-lettura.png 1080w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/03\/Club-di-lettura-240x300.png 240w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/03\/Club-di-lettura-819x1024.png 819w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/03\/Club-di-lettura-768x960.png 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\"  title=\"Club di lettura\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mer 29 Apr 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/caffe-letterario-alcide-pierantozzi\/\" title=\"Caff\u00e9 letterario |\u00a0Alcide Pierantozzi\">Caff\u00e9 letterario |\u00a0Alcide Pierantozzi<\/a><\/h5>\n                            <p class=\"card-text\">Ritorna il nostro appuntamento con l\u2019aperitivo letterario, il club di lettura dell\u2019IIC, che in questa occasione propone la lettura del romanzo Lo sbilico di Alcide Pierantozzi. Alcide ha quarant\u2019anni, a volte dorme ancora con sua madre, prende sette pasticche al giorno (cinque la mattina e due dopo cena), ed \u00e8 considerato \u00abun paziente lucido, vigile, [&hellip;]<\/p>\n                                <a title=\"Caff\u00e9 letterario |\u00a0Alcide Pierantozzi\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/caffe-letterario-alcide-pierantozzi\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/firarrels\/\" title=\"Leggi l'articolo: Firarrels\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"282\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/triptic-firarrels-2026_oficial_2_compressed-2_page-0001-1-300x282.jpg\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/triptic-firarrels-2026_oficial_2_compressed-2_page-0001-1.jpg 592w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/triptic-firarrels-2026_oficial_2_compressed-2_page-0001-1-300x282.jpg 300w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\"  title=\"triptic firarrels 2026_oficial_2_compressed (2)_page-0001 (1)\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Ven 24 Apr 2026<svg class=\"icon icon-xs icon-secondary me-1 ms-1\"><use href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use><\/svg>Dom 26 Apr 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/firarrels\/\" title=\"Firarrels\">Firarrels<\/a><\/h5>\n                            <p class=\"card-text\">Dal 24 al 26 aprile 2026, il comune di Tivenys ospita il festival culturale ed enogastronomico FirArrels Tivenys \u2013 Italia 2026: il festival \u00e8 un appuntamento culturale ed enogastronomico annuale, che in questa edizione \u00e8 dedicato alla valorizzazione della cultura italiana attraverso tradizioni, musica, gastronomia e spettacolo. La rassegna si arricchisce con la partecipazione straordinaria [&hellip;]<\/p>\n                                <a title=\"Firarrels\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/firarrels\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/xvii-festival-del-libro-dartista-e-della-piccola-edizione-2026\/\" title=\"Leggi l'articolo: XVII Festival del libro d\u2019artista e della piccola edizione 2026\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"300\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/circular-books-244x300.jpg\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/circular-books.jpg 1402w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/circular-books-244x300.jpg 244w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/circular-books-833x1024.jpg 833w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/circular-books-768x944.jpg 768w\" sizes=\"auto, (max-width: 1402px) 100vw, 1402px\"  title=\"circular books\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Gio 23 Apr 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/xvii-festival-del-libro-dartista-e-della-piccola-edizione-2026\/\" title=\"XVII Festival del libro d\u2019artista e della piccola edizione 2026\">XVII Festival del libro d\u2019artista e della piccola edizione 2026<\/a><\/h5>\n                            <p class=\"card-text\">In occasione della Giornata mondiale del libro Unesco e di Sant Jordi, torna il Festival del Libro d\u2019artista e della piccola edizione, promosso da Elisa Pellacani e Associaci\u00f3 ILDE in collaborazione con il Districte de Ciutat Vella e il Centre Civic Pati Llimona, con il patrocinio dell&#8217;Istituto Italiano di Cultura di Barcellona. Giunto alla sua [&hellip;]<\/p>\n                                <a title=\"XVII Festival del libro d\u2019artista e della piccola edizione 2026\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/xvii-festival-del-libro-dartista-e-della-piccola-edizione-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/giornata-della-ricerca-italiana-nel-mondo\/\" title=\"Leggi l'articolo: Giornata della ricerca italiana nel mondo\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"118\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/RicercaItaliana_NELMONDO_logo-BLU-300x118.jpg\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/RicercaItaliana_NELMONDO_logo-BLU.jpg 1920w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/RicercaItaliana_NELMONDO_logo-BLU-300x118.jpg 300w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/RicercaItaliana_NELMONDO_logo-BLU-1024x404.jpg 1024w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/RicercaItaliana_NELMONDO_logo-BLU-768x303.jpg 768w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\"  title=\"RicercaItaliana_NELMONDO_logo-BLU\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mer 22 Apr 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/giornata-della-ricerca-italiana-nel-mondo\/\" title=\"Giornata della ricerca italiana nel mondo\">Giornata della ricerca italiana nel mondo<\/a><\/h5>\n                            <p class=\"card-text\">Il 22 aprile, in onore della Premio Nobel Rita Levi-Montalcini, la rete diplomatico-consolare celebra la Giornata della Ricerca Italiana nel Mondo, istituita nel 2018 dal MUR insieme al MAECI e al Ministero della Salute, per promuovere il contributo dei ricercatori italiani al panorama scientifico e tecnologico internazionale. Nel tempo, numerosi sono stati gli eventi e [&hellip;]<\/p>\n                                <a title=\"Giornata della ricerca italiana nel mondo\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/giornata-della-ricerca-italiana-nel-mondo\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/l%ca%bcarchitettura-la-musica-e-il-vuoto\/\" title=\"Leggi l'articolo: L\u02bcarchitettura, la musica e il vuoto\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/IIC-Aperitivi-Ap22-212x300.jpg\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/IIC-Aperitivi-Ap22.jpg 1414w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/IIC-Aperitivi-Ap22-212x300.jpg 212w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/IIC-Aperitivi-Ap22-724x1024.jpg 724w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/IIC-Aperitivi-Ap22-768x1086.jpg 768w\" sizes=\"auto, (max-width: 1414px) 100vw, 1414px\"  title=\"IIC-Aperitivi-Ap2(2)\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Mar 21 Apr 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/l%ca%bcarchitettura-la-musica-e-il-vuoto\/\" title=\"L\u02bcarchitettura, la musica e il vuoto\">L\u02bcarchitettura, la musica e il vuoto<\/a><\/h5>\n                            <p class=\"card-text\">Evento speciale: l\u02bcarchitettura, la musica e il vuoto. Un\u02bcesplorazione dello spazio come materia creativa condivisa Con: Corrado Bolsi, Daria de Seta Un incontro tra architettura e musica per esplorare il silenzio, la risonanza e la proporzione come elementi vivi dello spazio. Il vuoto diventa protagonista: ricettore, scenario e parte attiva dell\u02bcesperienza architettonica e sonora. Interviene [&hellip;]<\/p>\n                                <a title=\"L\u02bcarchitettura, la musica e il vuoto\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/l%ca%bcarchitettura-la-musica-e-il-vuoto\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/domenica-italiana-al-festival-di-cinema-sant-jordi-bcn-film-fest-2026\/\" title=\"Leggi l'articolo: Domenica italiana al Festival di Cinema Sant Jordi &#8211; BCN Film FEST 2026\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/1-240x300.png\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/1.png 1080w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/1-240x300.png 240w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/1-819x1024.png 819w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/1-768x960.png 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\"  title=\"1\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Dom 19 Apr 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/domenica-italiana-al-festival-di-cinema-sant-jordi-bcn-film-fest-2026\/\" title=\"Domenica italiana al Festival di Cinema Sant Jordi &#8211; BCN Film FEST 2026\">Domenica italiana al Festival di Cinema Sant Jordi &#8211; BCN Film FEST 2026<\/a><\/h5>\n                            <p class=\"card-text\">L\u2019IIC \u00e8 lieto di collaborare alla decima edizione del BCN Film Fest (16-24 aprile), con una speciale \u201cdomenica italiana\u201d in cartellone: Primavera, di Damiano Michieletto, Duse, di Pietro Marcello e Nuovo Cinema Paradiso, di Giuseppe Tornatore. Il 19 aprile, una domenica speciale con una tripla sessione dedicata alla settima arte made in Italy: due film [&hellip;]<\/p>\n                                <a title=\"Domenica italiana al Festival di Cinema Sant Jordi &#8211; BCN Film FEST 2026\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/domenica-italiana-al-festival-di-cinema-sant-jordi-bcn-film-fest-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body row\">\n                                                    <div class=\"col-sm-3\">\n                                <div class=\"img-responsive\">\n                                    <figure class=\"img-wrapper\">\n                                        <a href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/il-mio-gaudi-di-chiara-curti\/\" title=\"Leggi l'articolo: Il mio Gaud\u00ed, di Chiara Curti\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/curti-300x300.jpg\" srcset=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/curti.jpg 1080w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/curti-300x300.jpg 300w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/curti-1024x1024.jpg 1024w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/curti-150x150.jpg 150w, https:\/\/iicbarcellona.esteri.it\/wp-content\/uploads\/2026\/04\/curti-768x768.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\"  title=\"curti\" alt=\"\" class=\"img-fluid\">\n                                                                                    <\/a>\n                                    <\/figure>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-9\">\n                                                            <div class=\"category-top\">\n                                    <span class=\"fw-bold text-danger\">Concluso<\/span>                                                                        <span class=\"data\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> Ven 17 Apr 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/il-mio-gaudi-di-chiara-curti\/\" title=\"Il mio Gaud\u00ed, di Chiara Curti\">Il mio Gaud\u00ed, di Chiara Curti<\/a><\/h5>\n                            <p class=\"card-text\">A 100 anni dalla scomparsa di Antoni Gaud\u00ed i Cornet, l\u2019architetta Chiara Curti ne traccia un ritratto intimo nel libro Il mio Gaud\u00ed, pubblicato in catalano in versione originale e tradotto in italiano con il supporto dell\u2019Istituto Italiano di Cultura di Barcellona.\u00a0La Comunit\u00e0 Cattolica Italiana a Barcellona organizza un evento di presentazione della versione italiana [&hellip;]<\/p>\n                                <a title=\"Il mio Gaud\u00ed, di Chiara Curti\" class=\"read-more\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/gli_eventi\/calendario\/il-mio-gaudi-di-chiara-curti\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                        <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n            \n            <div class=\"col-md-12 mt-4 pb-4\">\n                <nav class=\"navigation col-md-12\" aria-label=\"Navigation\">\n                    <h2 class=\"screen-reader-text visually-hidden\">Paginazione<\/h2>\n                    <div class=\"nav-links\">\n                    <span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036\/?pag=2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036\/?pag=3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036\/?pag=120\">120<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036\/?pag=2\"><svg class=\"icon icon-primary\"><use xlink:href=\"https:\/\/iicbarcellona.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-chevron-right\"><\/use><\/svg>\n                                    <span class=\"visually-hidden\">Pagina successiva<\/span><\/a>                    <\/div>\n                <\/nav>\n            <\/div>   <!--.col-md-12 -->\n              <\/div><!--.row -->\n              \n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp;","protected":false},"author":1,"featured_media":0,"parent":17,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7036","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=7036"}],"version-history":[{"count":1,"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036\/revisions"}],"predecessor-version":[{"id":7041,"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/7036\/revisions\/7041"}],"up":[{"embeddable":true,"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/pages\/17"}],"wp:attachment":[{"href":"https:\/\/iicbarcellona.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=7036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}